{"id":16624,"date":"2026-04-23T16:47:49","date_gmt":"2026-04-23T14:47:49","guid":{"rendered":"https:\/\/organicspharm.com\/?post_type=product&#038;p=16624"},"modified":"2026-04-27T14:48:53","modified_gmt":"2026-04-27T12:48:53","slug":"lip-mask","status":"publish","type":"product","link":"https:\/\/organicspharm.com\/en\/product\/lip-mask\/","title":{"rendered":"LIP MASK"},"content":{"rendered":"<p>Regala alle tue labbra un trattamento di puro nutrimento con la Lip Mask di Organics Pharm. Studiata specificamente per labbra secche e disidratate, questa maschera agisce in profondit\u00e0 per ripristinare elasticit\u00e0, comfort e un\u2019incredibile morbidezza. La sua ricca formulazione a base di oli vegetali pregiati crea un impacco emolliente che trasforma la texture delle labbra sin dalla prima applicazione. Ingredienti ChiaveOlio di Rosa Mosqueta Biologico: Noto per le sue straordinarie propriet\u00e0 rigeneranti ed elasticizzanti. Olio di Girasole &#038; Olio Essenziale di Arancio: Un mix nutriente e protettivo che dona comfort e una piacevole nota sensoriale. Estratti Botanici: Contiene Quillaja Saponaria e Saponaria Officinalis per una cura completa e naturale.<\/p>","protected":false},"excerpt":{"rendered":"<p>Maschera labbra ad azione nutriente e restitutiva. Contribuisce a migliorare morbidezza, elasticit\u00e0 e comfort delle labbra secche, disidratate o screpolate.<\/p>","protected":false},"featured_media":16625,"template":"","meta":{"_acf_changed":false,"_eb_attr":""},"product_brand":[],"product_cat":[941],"product_tag":[],"class_list":{"0":"post-16624","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-viso-e-skincare","7":"pa_linea-skin-care","8":"pa_trattamenti-specifici-idratazione-labbra","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LIP MASK - Organics Pharm Venice Italy<\/title>\n<meta name=\"description\" content=\"Trattamento di puro nutrimento con la Lip Mask di Organics Pharm. Studiata specificamente per labbra secche e disidratate.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/organicspharm.com\/en\/product\/lip-mask\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LIP MASK - Organics Pharm Venice Italy\" \/>\n<meta property=\"og:description\" content=\"Trattamento di puro nutrimento con la Lip Mask di Organics Pharm. Studiata specificamente per labbra secche e disidratate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/organicspharm.com\/en\/product\/lip-mask\/\" \/>\n<meta property=\"og:site_name\" content=\"Organics Pharm Venice Italy\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T12:48:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/organicspharm.com\/wp-content\/uploads\/2026\/04\/maschera-labbra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/lip-mask\\\/\",\"url\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/lip-mask\\\/\",\"name\":\"LIP MASK - Organics Pharm Venice Italy\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/lip-mask\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/lip-mask\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/maschera-labbra.jpg\",\"datePublished\":\"2026-04-23T14:47:49+00:00\",\"dateModified\":\"2026-04-27T12:48:53+00:00\",\"description\":\"Trattamento di puro nutrimento con la Lip Mask di Organics Pharm. Studiata specificamente per labbra secche e disidratate.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/lip-mask\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/lip-mask\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/lip-mask\\\/#primaryimage\",\"url\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/maschera-labbra.jpg\",\"contentUrl\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/maschera-labbra.jpg\",\"width\":1500,\"height\":1500,\"caption\":\"maschera-labbra\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/lip-mask\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/organicspharm.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/organicspharm.com\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LIP MASK\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#website\",\"url\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/\",\"name\":\"Organics Pharm Venice Italy\",\"description\":\"Per il tuo corpo, scegli la natura!\",\"publisher\":{\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#organization\",\"name\":\"Organics Pharm\",\"url\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/organics_pharm_footer.png\",\"contentUrl\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/organics_pharm_footer.png\",\"width\":200,\"height\":100,\"caption\":\"Organics Pharm\"},\"image\":{\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LIP MASK - Organics Pharm Venice Italy","description":"Trattamento di puro nutrimento con la Lip Mask di Organics Pharm. Studiata specificamente per labbra secche e disidratate.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/organicspharm.com\/en\/product\/lip-mask\/","og_locale":"en_US","og_type":"article","og_title":"LIP MASK - Organics Pharm Venice Italy","og_description":"Trattamento di puro nutrimento con la Lip Mask di Organics Pharm. Studiata specificamente per labbra secche e disidratate.","og_url":"https:\/\/organicspharm.com\/en\/product\/lip-mask\/","og_site_name":"Organics Pharm Venice Italy","article_modified_time":"2026-04-27T12:48:53+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/organicspharm.com\/wp-content\/uploads\/2026\/04\/maschera-labbra.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/organicspharm.com\/prodotto\/lip-mask\/","url":"https:\/\/organicspharm.com\/prodotto\/lip-mask\/","name":"LIP MASK - Organics Pharm Venice Italy","isPartOf":{"@id":"http:\/\/organicspharm.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/organicspharm.com\/prodotto\/lip-mask\/#primaryimage"},"image":{"@id":"https:\/\/organicspharm.com\/prodotto\/lip-mask\/#primaryimage"},"thumbnailUrl":"https:\/\/organicspharm.com\/wp-content\/uploads\/2026\/04\/maschera-labbra.jpg","datePublished":"2026-04-23T14:47:49+00:00","dateModified":"2026-04-27T12:48:53+00:00","description":"Trattamento di puro nutrimento con la Lip Mask di Organics Pharm. Studiata specificamente per labbra secche e disidratate.","breadcrumb":{"@id":"https:\/\/organicspharm.com\/prodotto\/lip-mask\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/organicspharm.com\/prodotto\/lip-mask\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/organicspharm.com\/prodotto\/lip-mask\/#primaryimage","url":"https:\/\/organicspharm.com\/wp-content\/uploads\/2026\/04\/maschera-labbra.jpg","contentUrl":"https:\/\/organicspharm.com\/wp-content\/uploads\/2026\/04\/maschera-labbra.jpg","width":1500,"height":1500,"caption":"maschera-labbra"},{"@type":"BreadcrumbList","@id":"https:\/\/organicspharm.com\/prodotto\/lip-mask\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/organicspharm.com\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/organicspharm.com\/prodotti\/"},{"@type":"ListItem","position":3,"name":"LIP MASK"}]},{"@type":"WebSite","@id":"http:\/\/organicspharm.com\/it\/#website","url":"http:\/\/organicspharm.com\/it\/","name":"Organics Pharm Venice Italy","description":"For your body, choose nature!","publisher":{"@id":"http:\/\/organicspharm.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/organicspharm.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/organicspharm.com\/it\/#organization","name":"Organics Pharm","url":"http:\/\/organicspharm.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/organicspharm.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/03\/organics_pharm_footer.png","contentUrl":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/03\/organics_pharm_footer.png","width":200,"height":100,"caption":"Organics Pharm"},"image":{"@id":"http:\/\/organicspharm.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product\/16624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/media\/16625"}],"wp:attachment":[{"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/media?parent=16624"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product_brand?post=16624"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product_cat?post=16624"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product_tag?post=16624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}