{"id":2425,"date":"2020-07-20T20:59:20","date_gmt":"2020-07-20T13:59:20","guid":{"rendered":"https:\/\/www.smastore.eu\/?post_type=product&#038;p=2425"},"modified":"2026-08-15T10:48:56","modified_gmt":"2026-08-15T08:48:56","slug":"shampoo-organico-post-colore","status":"publish","type":"product","link":"https:\/\/organicspharm.com\/en\/product\/shampoo-organic-post-color\/","title":{"rendered":"COLOR SAVE SHAMPO"},"content":{"rendered":"<p>Shampoo formulato per mantenere e ravvivare il colore dei capelli trattati o naturali. Deterge delicatamente cute e lunghezze, aiutando a riequilibrarle dopo il trattamento colorante. Grazie agli agenti idratanti, lascia i capelli morbidi, lucenti e setificati, prolungando la durata della colorazione. Ideale per l\u2019uso frequente, aiuta a prevenire l\u2019opacit\u00e0 e lo sbiadimento del colore.<\/p>","protected":false},"excerpt":{"rendered":"<p>Shampoo per esaltare il colore del capello naturale e trattato. Formulati per detergere e bilanciare cute e lunghezze dopo il trattamento colorante, prolungando la durata del colore.<\/p>","protected":false},"featured_media":2426,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[899],"product_tag":[292],"class_list":["post-2425","product","type-product","status-publish","has-post-thumbnail","product_cat-shampoo","product_tag-colore","pa_linea-color","pa_trattamenti-specifici-capelli-trattati","pa_trattamenti-specifici-mantenimento-colore","first","instock","featured","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COLOR SAVE SHAMPO - Organics Pharm Venice Italy<\/title>\n<meta name=\"description\" content=\"Shampoo organico dopo colore ad alto potere pulente, elimina le scorie dei trattamenti chimici aumentando la luminosit\u00e0 del colore e rallentandone lo sbiadimento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/organicspharm.com\/en\/product\/shampoo-organic-post-color\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COLOR SAVE SHAMPO - Organics Pharm Venice Italy\" \/>\n<meta property=\"og:description\" content=\"Shampoo organico dopo colore ad alto potere pulente, elimina le scorie dei trattamenti chimici aumentando la luminosit\u00e0 del colore e rallentandone lo sbiadimento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/organicspharm.com\/en\/product\/shampoo-organic-post-color\/\" \/>\n<meta property=\"og:site_name\" content=\"Organics Pharm Venice Italy\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-15T08:48:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/07\/Color-save-SH.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/shampoo-organico-post-colore\\\/\",\"url\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/shampoo-organico-post-colore\\\/\",\"name\":\"COLOR SAVE SHAMPO - Organics Pharm Venice Italy\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/shampoo-organico-post-colore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/shampoo-organico-post-colore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Color-save-SH.jpg\",\"datePublished\":\"2020-07-20T13:59:20+00:00\",\"dateModified\":\"2026-08-15T08:48:56+00:00\",\"description\":\"Shampoo organico dopo colore ad alto potere pulente, elimina le scorie dei trattamenti chimici aumentando la luminosit\u00e0 del colore e rallentandone lo sbiadimento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/shampoo-organico-post-colore\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/shampoo-organico-post-colore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/shampoo-organico-post-colore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Color-save-SH.jpg\",\"contentUrl\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Color-save-SH.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Color Save Shampoo After Coloring (Shampoo idratante dopo Colore)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/shampoo-organico-post-colore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/organicspharm.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/organicspharm.com\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COLOR SAVE SHAMPO\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#website\",\"url\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/\",\"name\":\"Organics Pharm Venice Italy\",\"description\":\"Per il tuo corpo, scegli la natura!\",\"publisher\":{\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#organization\",\"name\":\"Organics Pharm\",\"url\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/organics_pharm_footer.png\",\"contentUrl\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/organics_pharm_footer.png\",\"width\":200,\"height\":100,\"caption\":\"Organics Pharm\"},\"image\":{\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COLOR SAVE SHAMPO - Organics Pharm Venice Italy","description":"An organic after-color shampoo with high cleaning power, it removes the dross from chemical treatments while increasing color brightness and slowing fading.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/organicspharm.com\/en\/product\/shampoo-organic-post-color\/","og_locale":"en_US","og_type":"article","og_title":"COLOR SAVE SHAMPO - Organics Pharm Venice Italy","og_description":"Shampoo organico dopo colore ad alto potere pulente, elimina le scorie dei trattamenti chimici aumentando la luminosit\u00e0 del colore e rallentandone lo sbiadimento.","og_url":"https:\/\/organicspharm.com\/en\/product\/shampoo-organic-post-color\/","og_site_name":"Organics Pharm Venice Italy","article_modified_time":"2026-08-15T08:48:56+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/07\/Color-save-SH.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/organicspharm.com\/prodotto\/shampoo-organico-post-colore\/","url":"https:\/\/organicspharm.com\/prodotto\/shampoo-organico-post-colore\/","name":"COLOR SAVE SHAMPO - Organics Pharm Venice Italy","isPartOf":{"@id":"http:\/\/organicspharm.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/organicspharm.com\/prodotto\/shampoo-organico-post-colore\/#primaryimage"},"image":{"@id":"https:\/\/organicspharm.com\/prodotto\/shampoo-organico-post-colore\/#primaryimage"},"thumbnailUrl":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/07\/Color-save-SH.jpg","datePublished":"2020-07-20T13:59:20+00:00","dateModified":"2026-08-15T08:48:56+00:00","description":"An organic after-color shampoo with high cleaning power, it removes the dross from chemical treatments while increasing color brightness and slowing fading.","breadcrumb":{"@id":"https:\/\/organicspharm.com\/prodotto\/shampoo-organico-post-colore\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/organicspharm.com\/prodotto\/shampoo-organico-post-colore\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/organicspharm.com\/prodotto\/shampoo-organico-post-colore\/#primaryimage","url":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/07\/Color-save-SH.jpg","contentUrl":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/07\/Color-save-SH.jpg","width":1000,"height":1000,"caption":"Color Save Shampoo After Coloring (Shampoo idratante dopo Colore)"},{"@type":"BreadcrumbList","@id":"https:\/\/organicspharm.com\/prodotto\/shampoo-organico-post-colore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/organicspharm.com\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/organicspharm.com\/prodotti\/"},{"@type":"ListItem","position":3,"name":"COLOR SAVE SHAMPO"}]},{"@type":"WebSite","@id":"http:\/\/organicspharm.com\/it\/#website","url":"http:\/\/organicspharm.com\/it\/","name":"Organics Pharm Venice Italy","description":"For your body, choose nature!","publisher":{"@id":"http:\/\/organicspharm.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/organicspharm.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/organicspharm.com\/it\/#organization","name":"Organics Pharm","url":"http:\/\/organicspharm.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/organicspharm.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/03\/organics_pharm_footer.png","contentUrl":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/03\/organics_pharm_footer.png","width":200,"height":100,"caption":"Organics Pharm"},"image":{"@id":"http:\/\/organicspharm.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product\/2425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/media\/2426"}],"wp:attachment":[{"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/media?parent=2425"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product_brand?post=2425"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product_cat?post=2425"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product_tag?post=2425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}