{"id":2568,"date":"2020-08-13T16:48:24","date_gmt":"2020-08-13T09:48:24","guid":{"rendered":"https:\/\/www.smastore.eu\/?post_type=product&#038;p=2568"},"modified":"2026-08-15T10:48:57","modified_gmt":"2026-08-15T08:48:57","slug":"spray-districante-camomilla-patchouli","status":"publish","type":"product","link":"https:\/\/organicspharm.com\/en\/product\/spray-detangling-camomile-patchouli\/","title":{"rendered":"HYDRATE LEAVE IN SPRAY"},"content":{"rendered":"<p>Trattamento leave-in ideale per tutti i tipi di capelli. Questo spray districante e idratante apporta morbidezza, corpo e lucentezza, rendendo i capelli pi\u00f9 setosi e facili da pettinare fin dalla prima applicazione. La sua formula leggera non appesantisce e agisce in profondit\u00e0, nutrendo la fibra capillare e migliorando la texture del capello. Protegge efficacemente dai danni causati da fonte di calore (phon, piastra) e agenti esterni come vento, umidit\u00e0 e inquinamento. Perfetto per l\u2019uso quotidiano, lascia la chioma ordinata, luminosa e piacevolmente profumata, pronta per lo styling.<\/p>","protected":false},"excerpt":{"rendered":"<p>Spray senza risciacquo districante ed idratante. Dona setificazione corpo e lucentezza a qualsiasi tipo di capello, districandolo.<\/p>","protected":false},"featured_media":2579,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[934],"product_tag":[],"class_list":["post-2568","product","type-product","status-publish","has-post-thumbnail","product_cat-oli-styling","pa_linea-finishing","pa_trattamenti-specifici-capelli-normali","first","instock","featured","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HYDRATE LEAVE IN SPRAY - Organics Pharm Venice Italy<\/title>\n<meta name=\"description\" content=\"Spray senza risciacquo districante e idratante. Dona idratazione, corpo e lucentezza a qualsiasi tipo di capello, districandolo. Prodotto a base organica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/organicspharm.com\/en\/product\/spray-detangling-camomile-patchouli\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HYDRATE LEAVE IN SPRAY - Organics Pharm Venice Italy\" \/>\n<meta property=\"og:description\" content=\"Spray senza risciacquo districante e idratante. Dona idratazione, corpo e lucentezza a qualsiasi tipo di capello, districandolo. Prodotto a base organica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/organicspharm.com\/en\/product\/spray-detangling-camomile-patchouli\/\" \/>\n<meta property=\"og:site_name\" content=\"Organics Pharm Venice Italy\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-15T08:48:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/08\/Hydrate_leave_in_Spray.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/spray-districante-camomilla-patchouli\\\/\",\"url\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/spray-districante-camomilla-patchouli\\\/\",\"name\":\"HYDRATE LEAVE IN SPRAY - Organics Pharm Venice Italy\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/spray-districante-camomilla-patchouli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/spray-districante-camomilla-patchouli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Hydrate_leave_in_Spray.jpg\",\"datePublished\":\"2020-08-13T09:48:24+00:00\",\"dateModified\":\"2026-08-15T08:48:57+00:00\",\"description\":\"Spray senza risciacquo districante e idratante. Dona idratazione, corpo e lucentezza a qualsiasi tipo di capello, districandolo. Prodotto a base organica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/spray-districante-camomilla-patchouli\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/spray-districante-camomilla-patchouli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/spray-districante-camomilla-patchouli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Hydrate_leave_in_Spray.jpg\",\"contentUrl\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Hydrate_leave_in_Spray.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Hydrate Leave in Spray (Districante senza Risciacquo)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/organicspharm.com\\\/prodotto\\\/spray-districante-camomilla-patchouli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/organicspharm.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/organicspharm.com\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HYDRATE LEAVE IN SPRAY\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#website\",\"url\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/\",\"name\":\"Organics Pharm Venice Italy\",\"description\":\"Per il tuo corpo, scegli la natura!\",\"publisher\":{\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#organization\",\"name\":\"Organics Pharm\",\"url\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/organics_pharm_footer.png\",\"contentUrl\":\"https:\\\/\\\/organicspharm.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/organics_pharm_footer.png\",\"width\":200,\"height\":100,\"caption\":\"Organics Pharm\"},\"image\":{\"@id\":\"http:\\\/\\\/organicspharm.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HYDRATE LEAVE IN SPRAY - Organics Pharm Venice Italy","description":"Detangling and moisturizing no-rinse spray. Gives hydration, body and shine to any hair type while detangling it. Organic-based product.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/organicspharm.com\/en\/product\/spray-detangling-camomile-patchouli\/","og_locale":"en_US","og_type":"article","og_title":"HYDRATE LEAVE IN SPRAY - Organics Pharm Venice Italy","og_description":"Spray senza risciacquo districante e idratante. Dona idratazione, corpo e lucentezza a qualsiasi tipo di capello, districandolo. Prodotto a base organica.","og_url":"https:\/\/organicspharm.com\/en\/product\/spray-detangling-camomile-patchouli\/","og_site_name":"Organics Pharm Venice Italy","article_modified_time":"2026-08-15T08:48:57+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/08\/Hydrate_leave_in_Spray.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/organicspharm.com\/prodotto\/spray-districante-camomilla-patchouli\/","url":"https:\/\/organicspharm.com\/prodotto\/spray-districante-camomilla-patchouli\/","name":"HYDRATE LEAVE IN SPRAY - Organics Pharm Venice Italy","isPartOf":{"@id":"http:\/\/organicspharm.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/organicspharm.com\/prodotto\/spray-districante-camomilla-patchouli\/#primaryimage"},"image":{"@id":"https:\/\/organicspharm.com\/prodotto\/spray-districante-camomilla-patchouli\/#primaryimage"},"thumbnailUrl":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/08\/Hydrate_leave_in_Spray.jpg","datePublished":"2020-08-13T09:48:24+00:00","dateModified":"2026-08-15T08:48:57+00:00","description":"Detangling and moisturizing no-rinse spray. Gives hydration, body and shine to any hair type while detangling it. Organic-based product.","breadcrumb":{"@id":"https:\/\/organicspharm.com\/prodotto\/spray-districante-camomilla-patchouli\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/organicspharm.com\/prodotto\/spray-districante-camomilla-patchouli\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/organicspharm.com\/prodotto\/spray-districante-camomilla-patchouli\/#primaryimage","url":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/08\/Hydrate_leave_in_Spray.jpg","contentUrl":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/08\/Hydrate_leave_in_Spray.jpg","width":1000,"height":1000,"caption":"Hydrate Leave in Spray (Districante senza Risciacquo)"},{"@type":"BreadcrumbList","@id":"https:\/\/organicspharm.com\/prodotto\/spray-districante-camomilla-patchouli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/organicspharm.com\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/organicspharm.com\/prodotti\/"},{"@type":"ListItem","position":3,"name":"HYDRATE LEAVE IN SPRAY"}]},{"@type":"WebSite","@id":"http:\/\/organicspharm.com\/it\/#website","url":"http:\/\/organicspharm.com\/it\/","name":"Organics Pharm Venice Italy","description":"For your body, choose nature!","publisher":{"@id":"http:\/\/organicspharm.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/organicspharm.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/organicspharm.com\/it\/#organization","name":"Organics Pharm","url":"http:\/\/organicspharm.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/organicspharm.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/03\/organics_pharm_footer.png","contentUrl":"https:\/\/organicspharm.com\/wp-content\/uploads\/2020\/03\/organics_pharm_footer.png","width":200,"height":100,"caption":"Organics Pharm"},"image":{"@id":"http:\/\/organicspharm.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product\/2568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/media\/2579"}],"wp:attachment":[{"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/media?parent=2568"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product_brand?post=2568"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product_cat?post=2568"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/organicspharm.com\/en\/wp-json\/wp\/v2\/product_tag?post=2568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}